{"id":39,"date":"2021-12-30T04:44:20","date_gmt":"2021-12-30T04:44:20","guid":{"rendered":"http:\/\/systel-global.com\/peru\/blog\/producto\/fasticket\/"},"modified":"2022-04-12T23:18:09","modified_gmt":"2022-04-13T04:18:09","slug":"fasticket","status":"publish","type":"producto","link":"https:\/\/systel-global.com\/peru\/producto\/fasticket\/","title":{"rendered":"Fasticket"},"content":{"rendered":"\n<section class=\"wp-block-uagb-section uagb-section__wrap uagb-section__background-undefined uagb-block-115216db\"><div class=\"uagb-section__overlay\"><\/div><div class=\"uagb-section__inner-wrap\">\n<section class=\"wp-block-uagb-columns uagb-columns__wrap uagb-columns__background-undefined uagb-columns__stack-mobile uagb-columns__valign-undefined uagb-columns__gap-10 alignundefined uagb-block-49210500\"><div class=\"uagb-columns__overlay\"><\/div><div class=\"uagb-columns__inner-wrap uagb-columns__columns-2\">\n<div class=\"wp-block-uagb-column uagb-column__wrap uagb-column__background-undefined uagb-block-d742fddd\"><div class=\"uagb-column__overlay\"><\/div><div class=\"uagb-column__inner-wrap\">\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"900\" height=\"900\" src=\"https:\/\/systel-global.com\/peru\/wp-content\/uploads\/sites\/10\/2022\/01\/producto-fasticket-nw-01-900x900.jpg\" alt=\"\" class=\"wp-image-825\" title=\"\" srcset=\"https:\/\/systel-global.com\/peru\/wp-content\/uploads\/sites\/10\/2022\/01\/producto-fasticket-nw-01-900x900.jpg 900w, https:\/\/systel-global.com\/peru\/wp-content\/uploads\/sites\/10\/2022\/01\/producto-fasticket-nw-01-700x700.jpg 700w, https:\/\/systel-global.com\/peru\/wp-content\/uploads\/sites\/10\/2022\/01\/producto-fasticket-nw-01-400x400.jpg 400w, https:\/\/systel-global.com\/peru\/wp-content\/uploads\/sites\/10\/2022\/01\/producto-fasticket-nw-01-768x768.jpg 768w, https:\/\/systel-global.com\/peru\/wp-content\/uploads\/sites\/10\/2022\/01\/producto-fasticket-nw-01.jpg 1080w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" \/><\/figure><\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-column uagb-column__wrap uagb-column__background-undefined uagb-block-b85a62fd\"><div class=\"uagb-column__overlay\"><\/div><div class=\"uagb-column__inner-wrap\">\n<h1 class=\"wp-block-heading\">FASTICKET<\/h1>\n\n\n\n<p>Impresor t\u00e9rmico de papel continuo &#8211; Comandera.<\/p>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>Modelo: FASTICKET<\/p>\n\n\n\n<p>Tipo de soluci\u00f3n: Comercial<\/p>\n\n\n\n<p>Impresor t\u00e9rmico de papel continuo<\/p>\n\n\n\n<p>Auto corte incorporado<\/p>\n\n\n\n<p>Capacidad de ancho de papel de hasta 80mm<\/p>\n\n\n\n<p>Velocidad de impresi\u00f3n de 200mm\/seg.<\/p>\n\n\n\n<p>Dise\u00f1o compacto y est\u00e9tico<\/p>\n\n\n\n<p>Se\u00f1alizaci\u00f3n en frente del impresor, de f\u00e1cil lectura. Indicando: Energ\u00eda, Falta de papel,<\/p>\n\n\n\n<p>Detecci\u00f3n de errores<\/p>\n\n\n\n<p>Conexi\u00f3n con PC: A trav\u00e9s de conexi\u00f3n USB y Ethernet<\/p>\n\n\n\n<p>Compatible con PC: M\u00faltiples Sistemas Operativos<\/p>\n\n\n\n<p>Soporta impresi\u00f3n de los principales c\u00f3digos utilizados en la actualidad<\/p>\n\n\n\n<p>Compatible tambi\u00e9n con Caj\u00f3n Monedero.<\/p>\n\n\n\n<p>Dimensiones: 183.3 \u00d7140\u00d7141.5 mm<\/p>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button is-style-outline is-style-outline--1\"><a class=\"wp-block-button__link\" href=\"#consultar\">Consultar por el producto<\/a><\/div>\n<\/div>\n<\/div><\/div>\n<\/div><\/section>\n<\/div><\/section>\n\n\n<section class=\"mt-100\"><div class=\"container pc-m\"><div class=\"row\"><div class=\"col-12 col-md-12\"><h3>Especificaciones<\/h3><hr><\/div> <\/div><div class=\"row pt-5 pb-5\"><div class=\"col-6 col-md-4 mb-4\"><div class=\"data\"><div class=\"data-left\"><img decoding=\"async\" src=\"https:\/\/systel-global.com\/peru\/wp-content\/themes\/Systel\/assets\/images\/especificaciones\/icono-papel.png\" alt=\"\" title=\"\"><\/div><p class=\"especificacion\">TIPO DE PAPEL<br><span>Ticket<\/span><\/p><\/div><\/div><div class=\"col-6 col-md-4 mb-4\"><div class=\"data\"><div class=\"data-left\"><img decoding=\"async\" src=\"https:\/\/systel-global.com\/peru\/wp-content\/themes\/Systel\/assets\/images\/especificaciones\/icono-conectividad.png\" alt=\"\" title=\"\"><\/div><p class=\"especificacion\">CONECTIVIDAD<br><span>USB y ETH<\/span><\/p><\/div><\/div><\/div><\/div><\/section>\n\n\n\n<section class=\"wp-block-uagb-section uagb-section__wrap uagb-section__background-undefined uagb-block-efaf3068\"><div class=\"uagb-section__overlay\"><\/div><div class=\"uagb-section__inner-wrap\">\n<h3 class=\"wp-block-heading\">Caracter\u00edsticas<\/h3>\n\n\n\n<hr class=\"wp-block-separator is-style-wide\"\/>\n\n\n\n<div class=\"wp-block-columns featured-ul is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:50%\">\n<p>Velocidad de impresi\u00f3n<\/p>\n\n\n\n<p>Ancho de papel m\u00e1x.<\/p>\n\n\n\n<p>\u00c1rea imprimible<\/p>\n\n\n\n<p>Capacidad de columnas<\/p>\n\n\n\n<p>Espacio de l\u00edneas<\/p>\n\n\n\n<p>Vida \u00fatil de auto-corte<\/p>\n\n\n\n<p>Vida \u00fatil de cabezal de impresi\u00f3n<\/p>\n\n\n\n<p>Resoluci\u00f3n<\/p>\n\n\n\n<p>Potencia M\u00e1x.<\/p>\n\n\n\n<p>Potencia en reposo.<\/p>\n\n\n\n<p>Input buffer<\/p>\n\n\n\n<p>NV Flash<\/p>\n\n\n\n<p>Power adaptor<\/p>\n\n\n\n<p>Power source<\/p>\n\n\n\n<p>Input Voltage<\/p>\n\n\n\n<p>Cash drawer output<\/p>\n\n\n\n<p>Soporta impresi\u00f3n de c\u00f3digos de barra<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>Sistemas Operativos<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<p>200mm\/s<\/p>\n\n\n\n<p>80mm<\/p>\n\n\n\n<p>72mm<\/p>\n\n\n\n<p>576 dots\/line 512 dots\/line<\/p>\n\n\n\n<p>3,75mm<\/p>\n\n\n\n<p>1,5 millones de cortes<\/p>\n\n\n\n<p>150km<\/p>\n\n\n\n<p>576 dot\/l\u00ednea de impresi\u00f3n o 512 dot\/mm<\/p>\n\n\n\n<p>60W<\/p>\n\n\n\n<p>1W<\/p>\n\n\n\n<p>64 Kbytes<\/p>\n\n\n\n<p>256 Kbytes<\/p>\n\n\n\n<p>AC 110V\/220V, 50~60Hz<\/p>\n\n\n\n<p>DC 24V\/2.5A<\/p>\n\n\n\n<p>DC 24V\/2.5A<\/p>\n\n\n\n<p>DC 24V\/1A<\/p>\n\n\n\n<p>UPC-A\/ UPC-E\/JAN13(EAN13) \/ JAN8(EAN8)\/ CODE93\/ ITF \/<br>CODABAR\/ CODE93\/ CODE 128\/ QRCODE\/ PDF417<\/p>\n\n\n\n<p>Win XP, Win Vista, Win 7, Win 8, Win 8.1, Win 10, Linux<\/p>\n<\/div>\n<\/div>\n<\/div><\/section>\n","protected":false},"excerpt":{"rendered":"<p>Impresor t\u00e9rmico de papel continuo &#8211; Comandera.<\/p>\n","protected":false},"author":1,"featured_media":825,"menu_order":0,"comment_status":"closed","ping_status":"open","template":"","format":"standard","categories":[],"tags":[],"tipo_de_productos":[8],"tipo_de_solucion":[4],"class_list":["post-39","producto","type-producto","status-publish","format-standard","has-post-thumbnail","hentry","tipo_de_productos-impresoras","tipo_de_solucion-comercial"],"acf":[],"uagb_featured_image_src":{"full":["https:\/\/systel-global.com\/peru\/wp-content\/uploads\/sites\/10\/2022\/01\/producto-fasticket-nw-01.jpg",1080,1080,false],"thumbnail":["https:\/\/systel-global.com\/peru\/wp-content\/uploads\/sites\/10\/2022\/01\/producto-fasticket-nw-01-400x400.jpg",400,400,true],"medium":["https:\/\/systel-global.com\/peru\/wp-content\/uploads\/sites\/10\/2022\/01\/producto-fasticket-nw-01-700x700.jpg",700,700,true],"medium_large":["https:\/\/systel-global.com\/peru\/wp-content\/uploads\/sites\/10\/2022\/01\/producto-fasticket-nw-01-768x768.jpg",768,768,true],"large":["https:\/\/systel-global.com\/peru\/wp-content\/uploads\/sites\/10\/2022\/01\/producto-fasticket-nw-01-900x900.jpg",900,900,true],"1536x1536":["https:\/\/systel-global.com\/peru\/wp-content\/uploads\/sites\/10\/2022\/01\/producto-fasticket-nw-01.jpg",1080,1080,false],"2048x2048":["https:\/\/systel-global.com\/peru\/wp-content\/uploads\/sites\/10\/2022\/01\/producto-fasticket-nw-01.jpg",1080,1080,false]},"uagb_author_info":{"display_name":"Systel Global","author_link":"https:\/\/systel-global.com\/peru\/author\/marcelobato\/"},"uagb_comment_info":0,"uagb_excerpt":"Impresor t\u00e9rmico de papel continuo - Comandera.","_links":{"self":[{"href":"https:\/\/systel-global.com\/peru\/wp-json\/wp\/v2\/producto\/39","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/systel-global.com\/peru\/wp-json\/wp\/v2\/producto"}],"about":[{"href":"https:\/\/systel-global.com\/peru\/wp-json\/wp\/v2\/types\/producto"}],"author":[{"embeddable":true,"href":"https:\/\/systel-global.com\/peru\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/systel-global.com\/peru\/wp-json\/wp\/v2\/comments?post=39"}],"version-history":[{"count":7,"href":"https:\/\/systel-global.com\/peru\/wp-json\/wp\/v2\/producto\/39\/revisions"}],"predecessor-version":[{"id":982,"href":"https:\/\/systel-global.com\/peru\/wp-json\/wp\/v2\/producto\/39\/revisions\/982"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/systel-global.com\/peru\/wp-json\/wp\/v2\/media\/825"}],"wp:attachment":[{"href":"https:\/\/systel-global.com\/peru\/wp-json\/wp\/v2\/media?parent=39"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/systel-global.com\/peru\/wp-json\/wp\/v2\/categories?post=39"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/systel-global.com\/peru\/wp-json\/wp\/v2\/tags?post=39"},{"taxonomy":"tipo_de_productos","embeddable":true,"href":"https:\/\/systel-global.com\/peru\/wp-json\/wp\/v2\/tipo_de_productos?post=39"},{"taxonomy":"tipo_de_solucion","embeddable":true,"href":"https:\/\/systel-global.com\/peru\/wp-json\/wp\/v2\/tipo_de_solucion?post=39"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}